{"id":33403,"date":"2022-09-26T05:00:00","date_gmt":"2022-09-26T10:00:00","guid":{"rendered":"https:\/\/iglesiapalabrapura.com\/site\/?p=33403"},"modified":"2022-09-26T09:32:01","modified_gmt":"2022-09-26T14:32:01","slug":"hechos-de-los-apostoles-parte-9","status":"publish","type":"post","link":"https:\/\/iglesiapalabrapura.com\/site\/2022\/09\/26\/hechos-de-los-apostoles-parte-9\/","title":{"rendered":"HECHOS DE LOS AP\u00d3STOLES &#8211; PARTE 9"},"content":{"rendered":"<p>Ya hemos contestado qui\u00e9n escribi\u00f3 Hechos de los Ap\u00f3stoles, para qui\u00e9n se escribi\u00f3, desde d\u00f3nde creemos se escribi\u00f3, y hoy espero que podamos contestar la cuarta pregunta. Empecemos:<\/p><p><strong>\u00bf<\/strong><strong>BAJO QU\u00c9 CONTEXTO SE ESCRIBI\u00d3?<\/strong><strong><\/strong><\/p><p>El Imperio Romano ven\u00eda conquistando naciones y estableciendo su cultura en ellas. Gran parte de los Jud\u00edos viv\u00edan en su tierra, pero no ten\u00edan soberan\u00eda sobre su naci\u00f3n. Luego de ser conquistados por los Babilonios no recuperaron su autonom\u00eda como naci\u00f3n, sino que pasaron consecutivamente por otras conquistas de otros imperios, como el Persa, el Griego y el Romano.<\/p><p>Los Romanos ten\u00edan el control Pol\u00edtico y Econ\u00f3mico en el tiempo del Ministerio de Jesucristo en la tierra, y la Iglesia naci\u00f3 bajo ese contexto hist\u00f3rico. Ante la conquista de los Romanos, los Jud\u00edos se divid\u00edan en 4 grupos de acuerdo a su reacci\u00f3n a la conquista del imperio Romano: Los Saduceos, los Fariseos, los Zelotes y los Esenios. Los Saduceos se caracterizaban por ser interesados y egoc\u00e9ntricos, se acomodaban a las exigencias del imperio Romano, siempre y cuando tuvieran parte en los altos cargos de autoridad; los Fariseos se caracterizaban por ser celosos de la Ley de Mois\u00e9s, buscaban cumplirla estrictamente; los Zelotes eran Jud\u00edos que se unieron para formar un grupo guerrillero que se levantaba con violencia contra Roma y sus impuestos; y los Esenios eran Jud\u00edos que se fueron a vivir al desierto como ermita\u00f1os.<\/p><p>Los Romanos establec\u00edan control en las naciones conquistadas, siempre dispuestos a castigar fuertemente al que se saliera del orden, pero permit\u00edan que las naciones mantuvieran sus creencias religiosas, as\u00ed como autonom\u00eda para establecer Juicios por incumplir mandamientos religiosos. Para este tiempo, Europa y Asia hab\u00edan adoptado el idioma Griego como lengua com\u00fan, y los Romanos no ten\u00edan problema en que esta siguiera siendo la lengua que predominaba la mayor\u00eda de naciones. Aunque el idioma oficial de los Romanos era el Lat\u00edn, este se hablaba normalmente para hablar de Leyes Romanas, mas para comunicaci\u00f3n general, se hablaba el Griego. Los Jud\u00edos aunque hablaban perfectamente el Hebreo, su lengua natal, tambi\u00e9n muchos de ellos hablaban un perfecto Griego.<\/p><p>Jud\u00edos se pod\u00edan encontrar en diferentes naciones, y no eran perseguidos por su proclamaci\u00f3n de adorar al \u00fanico Dios verdadero, s\u00f3lo porque ellos no estaban interesados en convertir a absolutamente nadie; simplemente se era Jud\u00edo por venir de padres Jud\u00edos, y segu\u00edan sus tradiciones Jud\u00edas sin \u201cincomodar\u201d al resto de pueblos paganos, adoradores de piedras y maderas, y practicantes de inmoralidades sexuales.<\/p><p>Hechos de los Ap\u00f3stoles es un libro que narra la historia desde la Ascensi\u00f3n de Jes\u00fas, luego de pedirle a los Ap\u00f3stoles que esperaran al Esp\u00edritu Santo, hasta el Ap\u00f3stol Pablo en Roma, en casa por c\u00e1rcel, esperando presentarse a&nbsp;juicio. Una vez nace la Iglesia de Jesucristo, y comisionada para llamar a las naciones al arrepentimiento y conversi\u00f3n al \u00fanico Dios verdadero empieza su labor evangel\u00edstica (Mateo 28:19-20\/Hechos 1:8), los Jud\u00edos que no reconocieron al Mes\u00edas empezaron a perseguir a la Iglesia.<\/p><p>Donde llegaba el Evangelio, los Jud\u00edos que no se convert\u00edan ante el mensaje persegu\u00edan a los convertidos; los denunciaban y hasta los llevaban a la muerte. Para los Romanos, lo que estaba sucediendo no representaba inicialmente un problema para ellos, ya que estaban acostumbrados a ver a los Jud\u00edos juzgar a muerte a aquellos que no se acomodaran a sus costumbres, y para los Romanos, mientras siguieran sujet\u00e1ndose a ellos y pagando sus impuestos, pod\u00edan mantener la distancia ante lo que para ellos era extra\u00f1o, ya que adorar a un s\u00f3lo Dios para ellos era rid\u00edculo.<\/p><p>Los Romanos s\u00f3lo empezaron a perseguir a los cristianos cuando estos no estaban dispuestos a dejar de predicar el mensaje de las Buenas Noticias, llamando a las naciones a arrepentirse de su pecaminosa manera de vivir y a rendir lealtad m\u00e1xima al \u00fanico Dios verdadero. Ahora los cristianos ten\u00edan a Jesucristo como Kyrios (Se\u00f1or) Supremo, y no al Cesar, a quienes los Romanos llamaban Kyrios. Fue esto lo que puso en la mira a los cristianos ante el imperio Romano.<\/p><p>As\u00ed que podemos decir que Lucas escribi\u00f3 este Libro, Hechos de los Ap\u00f3stoles, bajo la persecuci\u00f3n. El Ap\u00f3stol Pablo, quien hab\u00eda perseguido a la Iglesia como Fariseo, se hab\u00eda convertido al Se\u00f1or Jesucristo, y ven\u00eda llevando la revelaci\u00f3n de la Gracia en sus viajes Misioneros al mundo Gentil. Por eso los Jud\u00edos, con sus ojos velados a la verdad, incitados por satan\u00e1s, fueron como aguijones en el costado de Pablo. Los Jud\u00edos lo persegu\u00edan para levantarle falsas acusaciones, que finalmente dieron fruto, llevando a Pablo al martirio. Lucas estuvo como fiel colaborador de Pablo, y tuvo que sentir esta tensi\u00f3n y amenaza de muerte constante. Sin embargo, Lucas hab\u00eda tomado su cruz y seguido a Cristo (Mateo 16:24), y no se acobard\u00f3 ante la tensi\u00f3n de anunciar el Evangelio de la Gracia. Estuvo dispuesto a seguir documentando los Hechos de la Iglesia.<\/p><p>Ahora, hasta esta parte he narrado el contexto por parte de los perseguidores del mensaje de Salvaci\u00f3n. Pero tambi\u00e9n debemos notar que la Iglesia, aunque experimentaba gran persecuci\u00f3n, tambi\u00e9n experimentaba grandes avivamientos. Jesucristo hab\u00eda dicho que la Palabra saldr\u00eda de Jerusal\u00e9n, hacia Judea, Samaria y hasta lo \u00faltimo de la tierra (Hechos 1:8), y es lo que estaba ocurriendo. Aunque los cristianos sufr\u00edan de manera injusta persecuci\u00f3n, su dispersi\u00f3n dio fruto para seguir extendi\u00e9ndose. Gracias a la salida de los creyentes de Jerusal\u00e9n, se dieron avivamientos como los de Samaria, Antioqu\u00eda de Siria y \u00c9feso.<\/p><p><strong>SAMARIA: <\/strong>\u201cAs\u00ed que los creyentes que se esparcieron predicaban la Buena Noticia acerca de Jes\u00fas adondequiera que iban.&nbsp;Felipe, por ejemplo, se dirigi\u00f3 a la ciudad de Samaria y all\u00ed le cont\u00f3 a la gente acerca del Mes\u00edas.&nbsp;Las multitudes escuchaban atentamente a Felipe, porque estaban deseosas de o\u00edr el mensaje y ver las se\u00f1ales milagrosas que \u00e9l hac\u00eda\u201d (Hechos 8:4-6 [NTV]).<\/p><p><strong>ANTIOQU\u00cdA DE SIRIA: <\/strong>\u201cSin embargo, algunos de los creyentes que fueron a Antioqu\u00eda desde Chipre y Cirene les comenzaron a predicar a los gentiles&nbsp;acerca del Se\u00f1or Jes\u00fas.&nbsp;El poder del Se\u00f1or estaba con ellos, y un gran n\u00famero de estos gentiles crey\u00f3 y se convirti\u00f3 al Se\u00f1or\u201d (Hechos 11:20-21 [NTV]).<\/p><p><strong>\u00c9FESO: <\/strong>\u201cLuego Pablo fue a la sinagoga y predic\u00f3 con valent\u00eda durante los siguientes tres meses, discutiendo persuasivamente sobre el reino de Dios;&nbsp;pero algunos se pusieron tercos, rechazaron el mensaje y hablaron p\u00fablicamente en contra del Camino. As\u00ed que Pablo sali\u00f3 de la sinagoga y se llev\u00f3 a los creyentes con \u00e9l. Entonces asist\u00eda diariamente a la sala de conferencias de Tirano, donde expon\u00eda sus ideas y debat\u00eda.&nbsp;Esto continu\u00f3 los siguientes dos a\u00f1os, de modo que gente de toda la provincia de Asia\u2014tanto jud\u00edos como griegos\u2014oy\u00f3 la palabra del Se\u00f1or. Dios le dio a Pablo el poder para realizar milagros excepcionales.&nbsp;Cuando pon\u00edan sobre los enfermos pa\u00f1uelos o delantales que apenas hab\u00edan tocado la piel de Pablo, quedaban sanos de sus enfermedades y los esp\u00edritus malignos sal\u00edan de ellos\u201d (Hechos 19:8-12 [NTV]).<\/p><p>Entonces, podemos concluir que Lucas escribi\u00f3 bajo un contexto de gran persecuci\u00f3n, pero que esta persecuci\u00f3n s\u00f3lo fue porque tambi\u00e9n se estaba viviendo gran avivamiento en muchos territorios, a causa del recibimiento del mensaje del Evangelio de la Gracia. En el pr\u00f3ximo art\u00edculo responderemos la \u00faltima pregunta de este m\u00e9todo de estudio de 5 preguntas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Imperio Romano ven\u00eda conquistando naciones y estableciendo su cultura en ellas. Gran parte de los Jud\u00edos viv\u00edan en su tierra, pero no ten\u00edan soberan\u00eda sobre su naci\u00f3n. Luego de ser conquistados por los Babilonios no recuperaron su autonom\u00eda como naci\u00f3n, sino que pasaron consecutivamente por otras conquistas de otros imperios, como el Persa, el Griego y el Romano.<\/p>\n","protected":false},"author":5,"featured_media":32829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[464,277],"class_list":["post-33403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulo","tag-hechos-de-los-apostoles","tag-pastor-rafael-lemes"],"_links":{"self":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts\/33403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/comments?post=33403"}],"version-history":[{"count":2,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts\/33403\/revisions"}],"predecessor-version":[{"id":33552,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts\/33403\/revisions\/33552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/media\/32829"}],"wp:attachment":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/media?parent=33403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/categories?post=33403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/tags?post=33403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}