{"id":72069,"date":"2025-07-04T05:00:00","date_gmt":"2025-07-04T10:00:00","guid":{"rendered":"https:\/\/iglesiapalabrapura.com\/site\/?p=72069"},"modified":"2026-02-05T15:05:00","modified_gmt":"2026-02-05T20:05:00","slug":"testimonios-55","status":"publish","type":"post","link":"https:\/\/iglesiapalabrapura.com\/site\/2025\/07\/04\/testimonios-55\/","title":{"rendered":"TESTIMONIOS"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><p class=\"15\"><b><strong><strong><strong><strong>Mi hija estaba al borde de la muerte, pero Dios la levant\u00f3<\/strong><\/strong><\/strong><\/strong><\/b><\/p><p class=\"15\"><\/p><\/h2><p>Mi nombre es Luz Marina Prieto, miembro de Iglesia Palabra Pura, y quiero compartir con ustedes uno de los momentos m\u00e1s duros pero tambi\u00e9n m\u00e1s gloriosos que he vivido como madre. Este testimonio tiene que ver con mi hija Mar\u00eda y lo que atravesamos durante la plandemia.<\/p><p>En medio de esos d\u00edas de tanta incertidumbre, a mi hija le dio una enfermedad respiratoria. Al principio parec\u00eda que iba a ser un cuadro leve, pero a los 20 d\u00edas su estado de salud se complic\u00f3 gravemente. Las plaquetas se le bajaron a cero y su cuerpo empez\u00f3 a debilitarse r\u00e1pidamente.<\/p><p>Ella estaba en un apartamento con un m\u00e9dico y un enfermero que la atend\u00edan en casa. Una ma\u00f1ana, el enfermero not\u00f3 que su estado era cr\u00edtico y llam\u00f3 de inmediato al m\u00e9dico. Al llegar, el doctor confirm\u00f3 que la situaci\u00f3n era delicad\u00edsima. La mir\u00f3, la trat\u00f3 y, en medio de esa escena desgarradora, le pregunt\u00f3 con qui\u00e9n quer\u00eda hablar, pero solo pod\u00eda ser con una persona\u2026 como para despedirse. Mi hija pidi\u00f3 hablar conmigo.<\/p><p>Fue un domingo a las cinco y media de la tarde. Recib\u00ed su llamada, y con una voz muy d\u00e9bil me dijo: \u201cMadre, ora porque estoy muy mal\u201d. Esas palabras me atravesaron el alma.<\/p><p>En ese momento, uno siente que el mundo se detiene. Que todo se derrumba. Que se le viene encima un baldado de agua hirviendo. Tambi\u00e9n habl\u00f3 con&nbsp;el esposo, quien, entre l\u00e1grimas, le dijo al m\u00e9dico:&nbsp;\u201cNo me vaya a dejar morir a la madre de mi hija, p\u00f3ngale lo que le tenga que poner, yo me hago cargo de todo.\u201d<\/p><p>El m\u00e9dico le respondi\u00f3 que le pondr\u00eda todo lo mejor, que no se iba a mover del lado de ella en toda la noche. Dijo algo que me marc\u00f3: \u201cYo har\u00e9 todo lo que me corresponde. El resto lo hace Dios\u201d. No s\u00e9 si ese m\u00e9dico era creyente, pero habl\u00f3 con una convicci\u00f3n que me dio paz.<\/p><p>Esa noche, termin\u00e9 de hacer la comida, y me fui al \u00faltimo rinc\u00f3n de mi casa. All\u00ed me arrodill\u00e9. Me postr\u00e9 con todo mi ser y empec\u00e9 a clamar. No ped\u00ed, declar\u00e9. Le dije a mi Padre: \u201cYo s\u00e9 en qui\u00e9n he cre\u00eddo. T\u00fa levantar\u00e1s a mi hija de ese lecho de dolor. T\u00fa eres mi Dios, el que no averg\u00fcenza a quienes en ti esperan\u201d.<\/p><p>Llor\u00e9 como una ni\u00f1a. Me encalambr\u00e9 de tanto tiempo que estuve de rodillas. En alg\u00fan momento me dorm\u00ed orando, y al despertar, a\u00fan con el dolor en mis piernas, no me levant\u00e9. Segu\u00ed declarando:&nbsp;\u201cT\u00fa me diste esta hija, T\u00fa me la restauras. Yo s\u00e9 en qui\u00e9n he cre\u00eddo.\u201d<\/p><p>El m\u00e9dico ya no permiti\u00f3 m\u00e1s llamadas esa noche. Solo dijo que al d\u00eda siguiente nos dar\u00eda el reporte. Yo no dorm\u00ed. A eso de las 6:30 a.\u202fm., ya no aguant\u00e9 m\u00e1s. Tom\u00e9 el tel\u00e9fono y llam\u00e9. Atendi\u00f3 mi nieta, que en ese momento ten\u00eda 10 a\u00f1os. Le ped\u00ed que fuera a preguntarle al m\u00e9dico c\u00f3mo hab\u00eda amanecido su mam\u00e1.<\/p><p>Al rato, la ni\u00f1a volvi\u00f3 al tel\u00e9fono y me dijo: \u201cAbuela, el m\u00e9dico dice que mi mam\u00e1 mejor\u00f3 durante la noche.\u201d En ese instante, volv\u00ed a ese rinc\u00f3n donde hab\u00eda clamado y solo pude agradecer.<\/p><p>\u00a1Dios la hab\u00eda sanado! El mismo m\u00e9dico dijo que hab\u00eda sido un milagro. Que \u00e9l esperaba que Mar\u00eda no amaneciera con vida, pero Dios ten\u00eda la \u00faltima palabra.<\/p><p>Hoy puedo testificar que mi hija vive por la misericordia de Dios. Que nuestra fe no es en vano. Que vale la pena clamar, declarar y confiar. Este es el Dios en el que hemos cre\u00eddo, y este es el testimonio que quer\u00eda compartir para Su gloria.<\/p><p><\/p>","protected":false},"excerpt":{"rendered":"<p>Mi nombre es Luz Marina Prieto, miembro de Iglesia Palabra Pura, y quiero compartir con ustedes uno de los momentos m\u00e1s duros pero tambi\u00e9n m\u00e1s gloriosos que he vivido como madre. Este testimonio tiene que ver con mi hija Mar\u00eda y lo que atravesamos durante la plandemia.<\/p>\n","protected":false},"author":2,"featured_media":72070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[472,1208,1209,468],"class_list":["post-72069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulo","tag-iglesia-palabra-pura","tag-mi-hija-estaba-al-borde-de-la-muerte","tag-pero-dios-la-levanto","tag-testimonios"],"_links":{"self":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts\/72069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/comments?post=72069"}],"version-history":[{"count":1,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts\/72069\/revisions"}],"predecessor-version":[{"id":72071,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/posts\/72069\/revisions\/72071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/media\/72070"}],"wp:attachment":[{"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/media?parent=72069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/categories?post=72069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iglesiapalabrapura.com\/site\/wp-json\/wp\/v2\/tags?post=72069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}